﻿{"id":3691,"date":"2026-05-13T10:58:36","date_gmt":"2026-05-13T08:58:36","guid":{"rendered":"http:\/\/www.sansebastiano.net\/?post_type=product&#038;p=3691"},"modified":"2026-06-10T15:05:28","modified_gmt":"2026-06-10T13:05:28","slug":"vendesi-macelleria-rosticceria-zona-pianta-forli-r44","status":"publish","type":"product","link":"https:\/\/www.sansebastiano.net\/index.php\/prodotto\/vendesi-macelleria-rosticceria-zona-pianta-forli-r44\/","title":{"rendered":"VENDESI MACELLERIA\/ROSTICCERIA ZONA PIANTA FORLI&#8217; &#8220;R44&#8221;"},"content":{"rendered":"<div class=\"gx-title-2 property-description__text\">Vendesi a Forl\u00ec macelleria\/gastronomia-rosticceria situata in zona residenziale e di forte passaggio, con ottima visibilit\u00e0. Locale completamente ristrutturato e arredato con gusto, dotato di splendido bancone a vista che valorizza l\u2019attivit\u00e0 e rende l\u2019ambiente moderno e accogliente. La cucina \u00e8 completa di attrezzature nuove e perfettamente funzionanti, ideale per lavorazioni di macelleria, gastronomia e rosticceria. Attivit\u00e0 pronta all\u2019uso, senza necessit\u00e0 di ulteriori investimenti. Completa la propriet\u00e0 area esterna con numerosi posti a sedere. Ottima opportunit\u00e0 per gestione familiare o per professionisti del settore alla ricerca di un locale ben avviato e curato nei dettagli. Richiesta: Euro 79.000 trattabili. Riferimento: Paolo 3494204529, Mail: svilupposansebastiano@gmail.com, Ufficio 0543 567203. La posizione inserita non \u00e8 precisa, per maggiori informazioni contattare l&#8217;agenzia. (Le seguenti informazioni non costituiscono elemento contrattuale.)<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vendesi a Forl\u00ec macelleria\/gastronomia-rosticceria situata in zona residenziale e di forte passaggio, con ottima visibilit\u00e0. Locale completamente ristrutturato e arredato con gusto, dotato di splendido bancone a vista che valorizza l\u2019attivit\u00e0 e rende l\u2019ambiente moderno e accogliente. La cucina \u00e8 completa di attrezzature nuove e perfettamente funzionanti, ideale per lavorazioni di macelleria, gastronomia e rosticceria. &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.sansebastiano.net\/index.php\/prodotto\/vendesi-macelleria-rosticceria-zona-pianta-forli-r44\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;VENDESI MACELLERIA\/ROSTICCERIA ZONA PIANTA FORLI&#8217; &#8220;R44&#8221;&#8221;<\/span><\/a><\/p>\n","protected":false},"featured_media":3699,"template":"","meta":{"spay_email":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>VENDESI MACELLERIA\/ROSTICCERIA ZONA PIANTA FORLI&#039; &quot;R44&quot; - San Sebastiano<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"http:\/\/www.sansebastiano.net\/index.php\/prodotto\/vendesi-macelleria-rosticceria-zona-pianta-forli-r44\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"VENDESI MACELLERIA\/ROSTICCERIA ZONA PIANTA FORLI&#039; &quot;R44&quot; - San Sebastiano\" \/>\r\n<meta property=\"og:description\" content=\"Vendesi a Forl\u00ec macelleria\/gastronomia-rosticceria situata in zona residenziale e di forte passaggio, con ottima visibilit\u00e0. Locale completamente ristrutturato e arredato con gusto, dotato di splendido bancone a vista che valorizza l\u2019attivit\u00e0 e rende l\u2019ambiente moderno e accogliente. La cucina \u00e8 completa di attrezzature nuove e perfettamente funzionanti, ideale per lavorazioni di macelleria, gastronomia e rosticceria. &hellip; Leggi tutto &quot;VENDESI MACELLERIA\/ROSTICCERIA ZONA PIANTA FORLI&#8217; &#8220;R44&#8221;&quot;\" \/>\r\n<meta property=\"og:url\" content=\"http:\/\/www.sansebastiano.net\/index.php\/prodotto\/vendesi-macelleria-rosticceria-zona-pianta-forli-r44\/\" \/>\r\n<meta property=\"og:site_name\" content=\"San Sebastiano\" \/>\r\n<meta property=\"article:modified_time\" content=\"2026-06-10T13:05:28+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.sansebastiano.net\/wp-content\/uploads\/2026\/05\/c4e5d0c7-68a2-4f47-9bb0-550f694af514.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1142\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sansebastiano.net\/#website\",\"url\":\"https:\/\/www.sansebastiano.net\/\",\"name\":\"San Sebastiano\",\"description\":\"Via Piero Maroncelli, n. 56, Forl\\u00ec (FC) 47122\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.sansebastiano.net\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.sansebastiano.net\/index.php\/prodotto\/vendesi-macelleria-rosticceria-zona-pianta-forli-r44\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.sansebastiano.net\/wp-content\/uploads\/2026\/05\/c4e5d0c7-68a2-4f47-9bb0-550f694af514.jpg\",\"width\":1600,\"height\":1142},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.sansebastiano.net\/index.php\/prodotto\/vendesi-macelleria-rosticceria-zona-pianta-forli-r44\/#webpage\",\"url\":\"http:\/\/www.sansebastiano.net\/index.php\/prodotto\/vendesi-macelleria-rosticceria-zona-pianta-forli-r44\/\",\"name\":\"VENDESI MACELLERIA\/ROSTICCERIA ZONA PIANTA FORLI' \\\"R44\\\" - San Sebastiano\",\"isPartOf\":{\"@id\":\"https:\/\/www.sansebastiano.net\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.sansebastiano.net\/index.php\/prodotto\/vendesi-macelleria-rosticceria-zona-pianta-forli-r44\/#primaryimage\"},\"datePublished\":\"2026-05-13T08:58:36+00:00\",\"dateModified\":\"2026-06-10T13:05:28+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.sansebastiano.net\/index.php\/prodotto\/vendesi-macelleria-rosticceria-zona-pianta-forli-r44\/\"]}]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.sansebastiano.net\/index.php\/wp-json\/wp\/v2\/product\/3691"}],"collection":[{"href":"https:\/\/www.sansebastiano.net\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.sansebastiano.net\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sansebastiano.net\/index.php\/wp-json\/wp\/v2\/media\/3699"}],"wp:attachment":[{"href":"https:\/\/www.sansebastiano.net\/index.php\/wp-json\/wp\/v2\/media?parent=3691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}